{"id":8370,"date":"2022-12-12T18:03:13","date_gmt":"2022-12-12T18:03:13","guid":{"rendered":"https:\/\/hyganfilter.com\/home\/site-repair\/"},"modified":"2026-02-10T10:26:07","modified_gmt":"2026-02-10T10:26:07","slug":"system_assesments","status":"publish","type":"page","link":"https:\/\/hyganfilter.com\/home\/system_assesments\/","title":{"rendered":"System Assessments"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8370\" class=\"elementor elementor-8370\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a45b89b elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"5a45b89b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c49a604\" data-id=\"7c49a604\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e07069c elementor-widget elementor-widget-vc_custom_heading\" data-id=\"7e07069c\" data-element_type=\"widget\" data-widget_type=\"vc_custom_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\" vc_custom_heading  consulting_heading_font  text_align_center has_subtitle stripe_between\" ><h2 style=\"color: #FFFFFF;text-align: center;font-weight:600\" class=\"consulting-custom-title\">System Assessments\n<\/h2><div class=\"subtitle\" style=\"color:#FFFFFF\">Ready for plant-wide lifecycle improvements?<\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1b3b7c01 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default\" data-id=\"1b3b7c01\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7a7e2b86\" data-id=\"7a7e2b86\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14678364 elementor-widget elementor-widget-heading\" data-id=\"14678364\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.4 - 12-03-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">System Assessments<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-733c843c elementor-widget elementor-widget-text-editor\" data-id=\"733c843c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.4 - 12-03-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>If your equipment can\u2019t come to us, we\u2019ll come to you. We understand the hassles and waste time that can accompany emergency repairs and the immediate need for a spare part. And we also understand the considerable time and effort needed for proper on-site installation and maintenance.<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bf1fcfe elementor-widget elementor-widget-button\" data-id=\"2bf1fcfe\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper icon_align_left  \">\n\t\t\t<a href=\"#\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Contact Us<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-99933ed\" data-id=\"99933ed\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9eb43d elementor-widget elementor-widget-stm_spacing\" data-id=\"f9eb43d\" data-element_type=\"widget\" data-widget_type=\"stm_spacing.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"stm-spacing\" id=\"stm-spacing-6a04657a724ff\"><\/div>\n<script>\n    (function($){\n        \"use strict\";\n        var spacingID = 'stm-spacing-6a04657a724ff',\n            lgSpacing = '',\n            mdSpacing = '',\n            smSpacing = '',\n            xsSpacing = '';\n\n        function stmSpacing() {\n            if ( window.matchMedia(\"(min-width: 1200px)\").matches && lgSpacing ) {\n                $( '#' + spacingID ).css ( \"height\", lgSpacing );\n            } else if ( window.matchMedia(\"(max-width: 1199px) and (min-width: 992px )\").matches && mdSpacing ) {\n                $( '#' + spacingID ).css ( \"height\", mdSpacing );\n            } else if ( window.matchMedia(\"(max-width: 991px) and (min-width: 768px )\").matches && smSpacing ) {\n                $( '#' + spacingID ).css ( \"height\", smSpacing );\n            } else if ( window.matchMedia(\"(max-width: 767px)\").matches && xsSpacing ) {\n                $( '#' + spacingID ).css ( \"height\", xsSpacing );\n            } else {\n                $( '#' + spacingID ).css ( \"height\", \"\" );\n            }\n        }\n\n        $(document).ready(function() {\n            stmSpacing();\n        });\n\n        $(window).resize(function() {\n            stmSpacing();\n        });\n\n    })(jQuery);\n<\/script>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15a4d91a elementor-widget__width-inherit elementor-widget elementor-widget-stm_sidebar\" data-id=\"15a4d91a\" data-element_type=\"widget\" data-widget_type=\"stm_sidebar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<div class=\"stm_sidebar consulting_elementor_sidebar\">\n\n            \t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"7556\" class=\"elementor elementor-7556\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d8f910e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d8f910e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b6ebfa\" data-id=\"4b6ebfa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f9c3cf hfe-nav-menu__align-left hfe-submenu-icon-arrow hfe-submenu-animation-none hfe-link-redirect-child hfe-nav-menu__breakpoint-tablet elementor-widget elementor-widget-navigation-menu\" data-id=\"5f9c3cf\" data-element_type=\"widget\" data-settings=\"{&quot;padding_horizontal_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_menu_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_row_space&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_row_space_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;menu_row_space_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;dropdown_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;dropdown_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;width_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;220&quot;,&quot;sizes&quot;:[]},&quot;width_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;width_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_horizontal_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;padding_vertical_dropdown_item_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;distance_from_menu_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;toggle_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"navigation-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"hfe-nav-menu hfe-layout-horizontal hfe-nav-menu-layout horizontal hfe-pointer__none\" data-layout=\"horizontal\">\n\t\t\t\t<div class=\"hfe-nav-menu__toggle elementor-clickable\">\n\t\t\t\t\t<div class=\"hfe-nav-menu-icon\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" tabindex=\"0\" class=\"fas fa-align-justify\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<nav class=\"hfe-nav-menu__layout-horizontal hfe-nav-menu__submenu-arrow\" data-toggle-icon=\"&lt;i aria-hidden=&quot;true&quot; tabindex=&quot;0&quot; class=&quot;fas fa-align-justify&quot;&gt;&lt;\/i&gt;\" data-close-icon=\"&lt;i aria-hidden=&quot;true&quot; tabindex=&quot;0&quot; class=&quot;far fa-window-close&quot;&gt;&lt;\/i&gt;\" data-full-width=\"yes\"><\/nav>              \n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-45c167e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45c167e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-45c1b05\" data-id=\"45c1b05\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45c2004 elementor-widget elementor-widget-wp-widget-nav_menu\" data-id=\"45c2004\" data-element_type=\"widget\" data-widget_type=\"wp-widget-nav_menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<aside class='widget widget_nav_menu'><div class=\"menu-service-expertise-container\"><ul id=\"menu-service-expertise\" class=\"menu\"><li id=\"menu-item-8310\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-8310\"><a href=\"https:\/\/hyganfilter.com\/home\/install\">Installation<\/a><\/li>\n<li id=\"menu-item-8311\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-8311\"><a href=\"https:\/\/hyganfilter.com\/home\/repair\">Site Repair &#038; Maintenance<\/a><\/li>\n<li id=\"menu-item-8312\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-8312\"><a href=\"https:\/\/hyganfilter.com\/home\/mro_motor_generator\">MRO Motor &#038; Generator<\/a><\/li>\n<li id=\"menu-item-8313\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-8313\"><a href=\"https:\/\/hyganfilter.com\/home\/assess\">System Assessments<\/a><\/li>\n<li id=\"menu-item-8314\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-8314\"><a href=\"https:\/\/hyganfilter.com\/home\/troubleshooting\">Troubleshooting<\/a><\/li>\n<\/ul><\/div><\/aside>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65de975 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"65de975\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper icon_align_left  \">\n\t\t\t<a href=\"https:\/\/hyganfilter.com\/home\/quote\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-left\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-copy\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Ask For Quotation<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t    \n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-219f7762 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"219f7762\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-19eeca6d\" data-id=\"19eeca6d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd0dc01 elementor-widget elementor-widget-heading\" data-id=\"fd0dc01\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Reduce critical equipment energy-use by assessing system performance.<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bfde538 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bfde538\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cc5a450\" data-id=\"cc5a450\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49d006a8 elementor-widget elementor-widget-text-editor\" data-id=\"49d006a8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>If your equipment can\u2019t come to us, we\u2019ll come to you. We understand the hassles and wasted time that can accompany emergency repairs and the immediate need for a spare part. And we also understand the considerable time and effort needed for proper on-site installation and maintenance.<\/p>\n<p>From maintenance to management, our highly qualified project managers, engineers and technicians can be on-site to help your operations run smoothly. We achieve this through the following comprehensive evaluation process:<\/p>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c67c6fa elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c67c6fa\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/hyganfilter.com\/home\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Define: Establish baselines on current equipment and operating performance.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Identify: Determine repairs, upgrades and improvements to enhance equipment performance.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Perform: Repair, upgrade and provide a recommendation to obtain optimum uptime and reliability.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Continuously monitor: Install near real-time monitoring systems to continuously measure system performance on an ongoing basis.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a340725\" data-id=\"a340725\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac53a87 elementor-widget elementor-widget-text-editor\" data-id=\"ac53a87\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ol>\n<li>Machining &amp; Repair Welding.<\/li>\n<li>Piping services.<\/li>\n<li>Mechanical upgrades &amp; retrofits.<\/li>\n<li>Installation &amp; strartup<br \/>Push pull services.<\/li>\n<li>Preventive &amp; scheduled maintenance.<\/li>\n<li>Turnkey maintenance.<\/li>\n<li>Troubleshooting, equipment testing &amp; non destructive examinations.<\/li>\n<li>Supervision &amp; project management.<\/li>\n<li>Scheduled inspections &amp; outage services.<\/li>\n<li>Startup &amp; operating procedure developments.<\/li>\n<\/ol>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8d0eb66 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8d0eb66\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cdda04a\" data-id=\"cdda04a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5d2e7c elementor-widget elementor-widget-heading\" data-id=\"c5d2e7c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Our Service level agreement will be the answer to drive reliability, safety, environmental and inventory efficiencies across your organization<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c22f6d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c22f6d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f62b821\" data-id=\"f62b821\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-388f3121 elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"388f3121\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;5&quot;,&quot;navigation&quot;:&quot;dots&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.4 - 12-03-2023 *\/\n.elementor-widget-image-carousel .swiper,.elementor-widget-image-carousel .swiper-container{position:static}.elementor-widget-image-carousel .swiper-container .swiper-slide figure,.elementor-widget-image-carousel .swiper .swiper-slide figure{line-height:inherit}.elementor-widget-image-carousel .swiper-slide{text-align:center}.elementor-image-carousel-wrapper:not(.swiper-container-initialized) .swiper-slide,.elementor-image-carousel-wrapper:not(.swiper-initialized) .swiper-slide{max-width:calc(100% \/ var(--e-image-carousel-slides-to-show, 3))}<\/style>\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"388f3121\" data-elementor-lightbox-title=\"WhatsApp Image 2022-09-16 at 18.02.47 (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzI2NCwidXJsIjoiaHR0cHM6XC9cL2h5Z2FuZmlsdGVyLmNvbVwvaG9tZVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAxNlwvMDFcL1doYXRzQXBwLUltYWdlLTIwMjItMDktMTYtYXQtMTguMDIuNDctMS5qcGVnIiwic2xpZGVzaG93IjoiMzg4ZjMxMjEifQ%3D%3D\" href=\"https:\/\/hyganfilter.com\/home\/wp-content\/uploads\/2016\/01\/WhatsApp-Image-2022-09-16-at-18.02.47-1.jpeg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/hyganfilter.com\/home\/wp-content\/uploads\/2016\/01\/WhatsApp-Image-2022-09-16-at-18.02.47-1.jpeg?resize=150%2C150&amp;ssl=1\" alt=\"WhatsApp Image 2022-09-16 at 18.02.47 (1)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"388f3121\" data-elementor-lightbox-title=\"WhatsApp Image 2022-09-16 at 18.02.48\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzI2NSwidXJsIjoiaHR0cHM6XC9cL2h5Z2FuZmlsdGVyLmNvbVwvaG9tZVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAxNlwvMDFcL1doYXRzQXBwLUltYWdlLTIwMjItMDktMTYtYXQtMTguMDIuNDguanBlZyIsInNsaWRlc2hvdyI6IjM4OGYzMTIxIn0%3D\" href=\"https:\/\/hyganfilter.com\/home\/wp-content\/uploads\/2016\/01\/WhatsApp-Image-2022-09-16-at-18.02.48.jpeg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/hyganfilter.com\/home\/wp-content\/uploads\/2016\/01\/WhatsApp-Image-2022-09-16-at-18.02.48.jpeg?resize=150%2C150&amp;ssl=1\" alt=\"WhatsApp Image 2022-09-16 at 18.02.48\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"388f3121\" data-elementor-lightbox-title=\"EXPLOSION DC\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzI2NiwidXJsIjoiaHR0cHM6XC9cL2h5Z2FuZmlsdGVyLmNvbVwvaG9tZVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAxNlwvMDFcL0VYUExPU0lPTi1EQy5qcGciLCJzbGlkZXNob3ciOiIzODhmMzEyMSJ9\" href=\"https:\/\/hyganfilter.com\/home\/wp-content\/uploads\/2016\/01\/EXPLOSION-DC.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/hyganfilter.com\/home\/wp-content\/uploads\/2016\/01\/EXPLOSION-DC.jpg?resize=150%2C150&amp;ssl=1\" alt=\"EXPLOSION DC\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"388f3121\" data-elementor-lightbox-title=\"WhatsApp Image 2021-09-08 at 07.35.16\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzI2NywidXJsIjoiaHR0cHM6XC9cL2h5Z2FuZmlsdGVyLmNvbVwvaG9tZVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAxNlwvMDFcL1doYXRzQXBwLUltYWdlLTIwMjEtMDktMDgtYXQtMDcuMzUuMTYuanBlZyIsInNsaWRlc2hvdyI6IjM4OGYzMTIxIn0%3D\" href=\"https:\/\/hyganfilter.com\/home\/wp-content\/uploads\/2016\/01\/WhatsApp-Image-2021-09-08-at-07.35.16.jpeg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/hyganfilter.com\/home\/wp-content\/uploads\/2016\/01\/WhatsApp-Image-2021-09-08-at-07.35.16.jpeg?resize=150%2C150&amp;ssl=1\" alt=\"WhatsApp Image 2021-09-08 at 07.35.16\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"388f3121\" data-elementor-lightbox-title=\"WhatsApp Image 2022-04-26 at 17.50.20\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NzI2OCwidXJsIjoiaHR0cHM6XC9cL2h5Z2FuZmlsdGVyLmNvbVwvaG9tZVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAxNlwvMDFcL1doYXRzQXBwLUltYWdlLTIwMjItMDQtMjYtYXQtMTcuNTAuMjAuanBlZyIsInNsaWRlc2hvdyI6IjM4OGYzMTIxIn0%3D\" href=\"https:\/\/hyganfilter.com\/home\/wp-content\/uploads\/2016\/01\/WhatsApp-Image-2022-04-26-at-17.50.20.jpeg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/hyganfilter.com\/home\/wp-content\/uploads\/2016\/01\/WhatsApp-Image-2022-04-26-at-17.50.20.jpeg?resize=150%2C150&amp;ssl=1\" alt=\"WhatsApp Image 2022-04-26 at 17.50.20\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>System Assessments Ready for plant-wide lifecycle improvements? System Assessments If your equipment can\u2019t come to us, we\u2019ll come to you. We understand the hassles and waste time that can accompany emergency repairs and the immediate need for a spare part. And we also understand the considerable time and effort needed for proper on-site installation and<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8370","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hyganfilter.com\/home\/wp-json\/wp\/v2\/pages\/8370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hyganfilter.com\/home\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hyganfilter.com\/home\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hyganfilter.com\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hyganfilter.com\/home\/wp-json\/wp\/v2\/comments?post=8370"}],"version-history":[{"count":26,"href":"https:\/\/hyganfilter.com\/home\/wp-json\/wp\/v2\/pages\/8370\/revisions"}],"predecessor-version":[{"id":9929,"href":"https:\/\/hyganfilter.com\/home\/wp-json\/wp\/v2\/pages\/8370\/revisions\/9929"}],"wp:attachment":[{"href":"https:\/\/hyganfilter.com\/home\/wp-json\/wp\/v2\/media?parent=8370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}